{"id":608,"date":"2024-05-13T10:48:30","date_gmt":"2024-05-13T08:48:30","guid":{"rendered":"https:\/\/bn-sportfoto.de\/briefmarken\/?p=608"},"modified":"2024-05-13T10:48:30","modified_gmt":"2024-05-13T08:48:30","slug":"ausgabe-4-2024-der-vereinsnachrichten-erschienen","status":"publish","type":"post","link":"https:\/\/bn-sportfoto.de\/briefmarken\/2024\/05\/13\/ausgabe-4-2024-der-vereinsnachrichten-erschienen\/","title":{"rendered":"Ausgabe 4 \/ 2024 der Vereinsnachrichten erschienen"},"content":{"rendered":"\n<p>Die \u201eGelsenkirchener Briefmarkenfreunde 1967 e. V. \u201c geben in unregelm\u00e4\u00dfigen Abst\u00e4nden gedruckte Vereinsnachrichten heraus.<\/p>\n\n\n\n<p>Ausgabe Nummer 4 erschien anl\u00e4sslich der Teilnahme an der Veranstaltung \u201eGl\u00fcck auf, Gelsenkirchen &#8211; Tag des Bergbaus 2024&#8243; am 12. Mai 2024 und kann <a href=\"http:\/\/www.bn-sportfoto.de\/briefmarken\/Vereinsnachrichten_04-2024.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">hier als PDF-Datei gelesen werden<\/a>.<\/p>\n\n\n\n<p><a href=\"http:\/\/www.bn-sportfoto.de\/briefmarken\/aktuelles\/vereinsnachrichten\/\">Alle bisher erschienenden Ausgaben finden Sie hier im Archiv.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die \u201eGelsenkirchener Briefmarkenfreunde 1967 e. V. \u201c geben in unregelm\u00e4\u00dfigen Abst\u00e4nden gedruckte Vereinsnachrichten heraus. Ausgabe Nummer 4 erschien anl\u00e4sslich der<\/p>\n","protected":false},"author":1,"featured_media":609,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[22,28,34,51,96,111,112],"class_list":["post-608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten","tag-bergbau","tag-briefmarken","tag-des","tag-gelsenkirchen","tag-tag","tag-veranstaltung","tag-vereinsnachrichten"],"_links":{"self":[{"href":"https:\/\/bn-sportfoto.de\/briefmarken\/wp-json\/wp\/v2\/posts\/608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bn-sportfoto.de\/briefmarken\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bn-sportfoto.de\/briefmarken\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bn-sportfoto.de\/briefmarken\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bn-sportfoto.de\/briefmarken\/wp-json\/wp\/v2\/comments?post=608"}],"version-history":[{"count":0,"href":"https:\/\/bn-sportfoto.de\/briefmarken\/wp-json\/wp\/v2\/posts\/608\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bn-sportfoto.de\/briefmarken\/wp-json\/wp\/v2\/media\/609"}],"wp:attachment":[{"href":"https:\/\/bn-sportfoto.de\/briefmarken\/wp-json\/wp\/v2\/media?parent=608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bn-sportfoto.de\/briefmarken\/wp-json\/wp\/v2\/categories?post=608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bn-sportfoto.de\/briefmarken\/wp-json\/wp\/v2\/tags?post=608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}