{"id":340,"date":"2023-01-01T13:00:00","date_gmt":"2023-01-01T12:00:00","guid":{"rendered":"https:\/\/bn-sportfoto.de\/briefmarken\/?p=340"},"modified":"2023-01-01T13:00:00","modified_gmt":"2023-01-01T12:00:00","slug":"tauschabende-im-jahr-2023","status":"publish","type":"post","link":"https:\/\/bn-sportfoto.de\/briefmarken\/2023\/01\/01\/tauschabende-im-jahr-2023\/","title":{"rendered":"Tauschabende im Jahr 2023"},"content":{"rendered":"\n<p>Eine \u00dcbersicht \u00fcber alle geplanten Termine der \u201eGelsenkirchener Briefmarkenfreunde 1967 e. V. \u201c und der \u201e Jungen Briefmarkenfreunde Gelsenkirchen-Mitte\u201c f\u00fcr das Jahr 2023 ist nun auf unserer Homepage zu finden. <\/p>\n\n\n\n<p>Die Jahreshauptversammlung des Vereins wird voraussichtlich im April 2023 stattfinden. Alle Mitglieder werden rechtzeitig vor dem Termin dazu eingeladen.<\/p>\n\n\n\n<p>Vormerken k\u00f6nnen sich alle Interessierten auch den Termin 1. November 2023. Dann findet der n\u00e4chste Gro\u00dftauschtag im Gemeindezentrum Rotthausen statt.<\/p>\n\n\n\n<p>Hier gelangen Sie direkt zur <a href=\"https:\/\/bn-sportfoto.de\/briefmarken\/termine\/\" data-type=\"page\" data-id=\"50\">Termin\u00fcbersicht<\/a>. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine \u00dcbersicht \u00fcber alle geplanten Termine der \u201eGelsenkirchener Briefmarkenfreunde 1967 e. V. \u201c und der \u201e Jungen Briefmarkenfreunde Gelsenkirchen-Mitte\u201c f\u00fcr<\/p>\n","protected":false},"author":1,"featured_media":341,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[28,37,51,54,56,61,88,100,104],"class_list":["post-340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten","tag-briefmarken","tag-dgb-haus-der-jugend","tag-gelsenkirchen","tag-gemeindezentrum","tag-grosstauschtag","tag-jahreshauptversammlung","tag-rotthausen","tag-tauschabend","tag-termine"],"_links":{"self":[{"href":"https:\/\/bn-sportfoto.de\/briefmarken\/wp-json\/wp\/v2\/posts\/340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bn-sportfoto.de\/briefmarken\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bn-sportfoto.de\/briefmarken\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bn-sportfoto.de\/briefmarken\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bn-sportfoto.de\/briefmarken\/wp-json\/wp\/v2\/comments?post=340"}],"version-history":[{"count":0,"href":"https:\/\/bn-sportfoto.de\/briefmarken\/wp-json\/wp\/v2\/posts\/340\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bn-sportfoto.de\/briefmarken\/wp-json\/wp\/v2\/media\/341"}],"wp:attachment":[{"href":"https:\/\/bn-sportfoto.de\/briefmarken\/wp-json\/wp\/v2\/media?parent=340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bn-sportfoto.de\/briefmarken\/wp-json\/wp\/v2\/categories?post=340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bn-sportfoto.de\/briefmarken\/wp-json\/wp\/v2\/tags?post=340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}